{"id":14436,"date":"2025-05-07T21:21:18","date_gmt":"2025-05-08T00:21:18","guid":{"rendered":"http:\/\/gilvander.org.br\/site\/?p=14436"},"modified":"2025-05-09T15:15:07","modified_gmt":"2025-05-09T18:15:07","slug":"por-que-e-justo-criar-rds-corregos-pocoes-tamandua-peixe-bravo-no-norte-de-minas-gerais-por-frei-gilvander","status":"publish","type":"post","link":"http:\/\/gilvander.org.br\/site\/por-que-e-justo-criar-rds-corregos-pocoes-tamandua-peixe-bravo-no-norte-de-minas-gerais-por-frei-gilvander\/","title":{"rendered":"POR QUE \u00c9 JUSTO CRIAR RDS C\u00d3RREGOS PO\u00c7\u00d5ES-TAMANDU\u00c1-PEIXE BRAVO NO NORTE DE MINAS GERAIS? Por frei Gilvander"},"content":{"rendered":"\n<p><strong>POR QUE \u00c9 JUSTO CRIAR RDS C\u00d3RREGOS PO\u00c7\u00d5ES-TAMANDU\u00c1-PEIXE BRAVO NO NORTE DE MINAS GERAIS?<\/strong> Por frei Gilvander Moreira<a id=\"_ftnref1\" href=\"#_ftn1\"><sup>[1]<\/sup><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide1-1024x768.jpg\" alt=\"\" class=\"wp-image-14437\" srcset=\"http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide1-1024x768.jpg 1024w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide1-300x225.jpg 300w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide1-768x576.jpg 768w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide1.jpg 1058w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Reprodu\u00e7\u00e3o Apresenta\u00e7\u00e3o do ICMBio<\/figcaption><\/figure>\n\n\n\n<p>O direito ao meio ambiente ecologicamente equilibrado est\u00e1 na Constitui\u00e7\u00e3o, no Art. 225 que diz: \u201c<em>Todos t\u00eam direito ao meio ambiente ecologicamente equilibrado, bem de uso comum do povo e essencial \u00e0 sadia qualidade de vida, impondo-se ao Poder P\u00fablico e \u00e0 coletividade o dever de defend\u00ea-lo e preserv\u00e1-lo para as presentes e futuras gera\u00e7\u00f5es<\/em>.&#8221;\u00a0<\/p>\n\n\n\n<p>H\u00e1 mais de vinte anos, Comunidades Geraizeiras, assentados da Reforma Agr\u00e1ria e Quilombo de Peixe Bravo reivindicam a cria\u00e7\u00e3o da Reserva de Desenvolvimento Sustent\u00e1vel (RDS) C\u00f3rregos Po\u00e7\u00f5es-Tamandu\u00e1-Peixe Bravo, no norte de Minas Gerais nos munic\u00edpios de Riacho dos Machados (82% da RDS = 44% da \u00e1rea do munic\u00edpio), Rio Pardo de Minas (11% da RDS = 2% da \u00e1rea do munic\u00edpio) e Serran\u00f3polis (8% da RDS = 6% da \u00e1rea do munic\u00edpio). Dias 25 e 26 de abril \u00faltimo (2025) aconteceram Consultas P\u00fablicas em Riacho dos Machados na Comunidade Quilombola de Peixe Bravo e na Comunidade Geraizeira de C\u00f3rrego Verde.<\/p>\n\n\n\n<p>Foram Consultas P\u00fablicas tensas, pois de um lado Comunidades Tradicionais e Quilombolas defenderam com \u00e9tica, ternura, m\u00edstica, poesia a necessidade da cria\u00e7\u00e3o da RDS C\u00f3rregos Po\u00e7\u00f5es-Tamandu\u00e1-Peixe Bravo, mas por outro lado, pessoas representando interesses de mineradoras, do agroneg\u00f3cio da monocultura do eucalipto e de pol\u00edticos de extrema-direita se posicionaram contra a cria\u00e7\u00e3o da RDS de uma forma muito agressiva, com vaias estridentes que violaram o direito de livre express\u00e3o e tentaram intimidar quem se posicionava a favor da RDS.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Mapa-para-criacao-da-RDS-Pocoes-Tamandua-e-Peixe-Bravo-no-norte-de-MG-28-04-25-1-1024x724.jpeg\" alt=\"\" class=\"wp-image-14442\" srcset=\"http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Mapa-para-criacao-da-RDS-Pocoes-Tamandua-e-Peixe-Bravo-no-norte-de-MG-28-04-25-1-1024x724.jpeg 1024w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Mapa-para-criacao-da-RDS-Pocoes-Tamandua-e-Peixe-Bravo-no-norte-de-MG-28-04-25-1-300x212.jpeg 300w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Mapa-para-criacao-da-RDS-Pocoes-Tamandua-e-Peixe-Bravo-no-norte-de-MG-28-04-25-1-768x543.jpeg 768w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Mapa-para-criacao-da-RDS-Pocoes-Tamandua-e-Peixe-Bravo-no-norte-de-MG-28-04-25-1-1536x1087.jpeg 1536w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Mapa-para-criacao-da-RDS-Pocoes-Tamandua-e-Peixe-Bravo-no-norte-de-MG-28-04-25-1.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Considerando os Direitos dos Povos e das Comunidades Tradicionais inscritos na Constitui\u00e7\u00e3o Federal, na Conven\u00e7\u00e3o 169 da OIT<a href=\"#_ftn1\" id=\"_ftnref1\">[1]<\/a> da ONU<a href=\"#_ftn2\" id=\"_ftnref2\">[2]<\/a>, a emerg\u00eancia clim\u00e1tica com eventos extremos cada vez mais frequentes e letais, o avan\u00e7o brutal das mineradoras, que onde se instalam causam brutal devasta\u00e7\u00e3o socioambiental (Veja a viol\u00eancia brutal imposta aos munic\u00edpios minerados, tais como Mariana, Brumadinho, Itabira, Concei\u00e7\u00e3o do Mato Dentro, Paracatu, Ara\u00e7ua\u00ed, Bar\u00e3o de Cocais&#8230;), a escassez h\u00eddrica crescente, a polui\u00e7\u00e3o das \u00e1guas, a extin\u00e7\u00e3o de nascentes, tudo em progress\u00e3o geom\u00e9trica, a responsabilidade socioambiental e geracional, temos que dialogar sobre v\u00e1rios pontos para que a verdade prevale\u00e7a e o bem comum seja o rumo orientador e n\u00e3o o \u00f3dio, a intoler\u00e2ncia e os interesses ego\u00edstas de uma minoria que se beneficiam com a devasta\u00e7\u00e3o imposta pelos brutais projetos de minera\u00e7\u00e3o e da monocultura do eucalipto que desertifica os territ\u00f3rios e dizima a exuber\u00e2ncia de biodiversidade que persiste nos cerrados, serras, nascentes e c\u00f3rregos&nbsp; que circundam os limites da Reserva de Desenvolvimento Sustent\u00e1vel.<\/p>\n\n\n\n<p>Importa recordar que o rio Peixe Bravo des\u00e1gua\/irriga o rio Vacaria, que des\u00e1gua no rio Jequitinhonha. Ou seja, se n\u00e3o for preservada a regi\u00e3o dos C\u00f3rregos Po\u00e7\u00f5es, Tamandu\u00e1 e Peixe Bravo, o j\u00e1 t\u00e3o agredido rio Jequitinhonha ter\u00e1 sua morte antecipada.<\/p>\n\n\n\n<p>Diante de informa\u00e7\u00f5es falsas e distorcidas que interessam \u00e0 mineradora Vale e outras mineradoras, aos agronegociantes da monocultura do eucalipto e a pol\u00edticos de extrema-direita que se beneficiam com a explora\u00e7\u00e3o da Natureza e dos Povos, o Instituto Chico Mendes de Conserva\u00e7\u00e3o da Biodiversidade (ICMBio) divulgou Nota P\u00fablica<a id=\"_ftnref3\" href=\"#_ftn3\">[3]<\/a> e nas Consultas P\u00fablicas apresentou em que consiste uma RDS: benef\u00edcios, o que pode, import\u00e2ncia, limites&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide2-1-1024x768.jpg\" alt=\"\" class=\"wp-image-14443\" srcset=\"http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide2-1-1024x768.jpg 1024w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide2-1-300x225.jpg 300w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide2-1-768x576.jpg 768w, http:\/\/gilvander.org.br\/site\/wp-content\/uploads\/2025\/05\/Slide2-1.jpg 1058w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Diz o ICMBio: &#8220;<em>A proposta de cria\u00e7\u00e3o da RDS C\u00f3rregos Tamandu\u00e1-Po\u00e7\u00f5es-Peixe Bravo foi reivindicada pelo movimento Geraizeiro na d\u00e9cada de 1990, para a prote\u00e7\u00e3o dos campos gerais (Cerrado), das cabeceiras de Rio (\u00e1reas de recarga h\u00eddrica) e do modo de vida tradicional das Comunidades Geraizeiras no norte de Minas Gerais. Posteriormente, a Comunidade do Quilombo de Peixe Bravo \u2013 j\u00e1 reconhecida pela Funda\u00e7\u00e3o Palmares -, cujo territ\u00f3rio j\u00e1 foi indicado em Estudo Antropol\u00f3gico, mas ainda n\u00e3o foi demarcado, aderiu \u00e0 mesma reivindica\u00e7\u00e3o, visando incorporar seu territ\u00f3rio na RDS C\u00f3rregos Tamandu\u00e1-Po\u00e7\u00f5es-Peixe Bravo, para tamb\u00e9m proteger seus recursos naturais e modo de vida. Ambas as Comunidades sofrem press\u00e3o de atividades econ\u00f4micas, em especial setores produtivos (mineradoras e monocultura do eucalipto), tanto l\u00edcitas quanto il\u00edcitas, que amea\u00e7am seus modos de vida e os recursos naturais presentes nos seus territ\u00f3rios.<\/em>\u201d<\/p>\n\n\n\n<p>\u201c<em>A RDS \u00e9 uma categoria de Unidade de Conserva\u00e7\u00e3o que pode garantir esta prote\u00e7\u00e3o ambiental reivindicada sem impactar ou restringir o modo de vida tradicional destas comunidades. As atividades ali j\u00e1 praticadas por diversas gera\u00e7\u00f5es t\u00eam se mostrado totalmente sustent\u00e1veis e protetoras da natureza.&nbsp;RDS n\u00e3o \u00e9 Parque. Agricultura familiar, solta de gado, coleta de frutos e outras esp\u00e9cies no Cerrado e na Mata, s\u00e3o totalmente compat\u00edveis e permitidas em uma RDS. Toda a infraestrutura necess\u00e1ria para as comunidades incluindo casas, currais, escola, hospital, estradas, casas de farinha, ind\u00fastrias para beneficiamento de frutas, entre tantas outras possibilidades tamb\u00e9m s\u00e3o permitidas em uma RDS<\/em>.\u201d&nbsp;<\/p>\n\n\n\n<p>\u201c<em>S\u00e3o permitidas tamb\u00e9m propriedades tituladas, posses e a titula\u00e7\u00e3o no interior da RDS. Contudo grandes fazendas ou propriedades em desacordo com os objetivos da RDS e com o modo de vida das popula\u00e7\u00f5es tradicionais podem ser indenizadas e desapropriadas pelo ICMBio para uso coletivo da comunidade<\/em>.\u201d Um presidente de Sindicato Rural tentou induzir propriet\u00e1rios de terra a se posicionarem contra a RDS alegando que no projeto da RDS est\u00e1 facultada a possibilidade de desapropria\u00e7\u00e3o de fazendas. No entanto, ele omitiu que segundo a Lei Geral de Desapropria\u00e7\u00e3o (DECRETO-LEI N\u00ba 3.365, de 21\/06\/1941) qualquer propriedade no Brasil, no campo ou na cidade, por interesse p\u00fablico, pode ser desapropriada pelo presidente, ou governador ou prefeito. N\u00e3o est\u00e1 mais vigente no Brasil a Constitui\u00e7\u00e3o Imperial de 1824 que garantia direito absoluto \u00e0 propriedade. Segundo a Constitui\u00e7\u00e3o Federal de 1988, toda propriedade deve cumprir sua fun\u00e7\u00e3o social, sen\u00e3o poder\u00e1 ser desapropriada, ap\u00f3s se declarar interesse p\u00fablico sobre ela, independente de estar dentro ou fora de uma RDS.<\/p>\n\n\n\n<p>Diz o ICMBio: \u201c<em>A gest\u00e3o da RDS \u00e9 feita de forma compartilhada com as comunidades por meio de um conselho deliberativo.&nbsp;A RDS C\u00f3rregos Tamandu\u00e1-Po\u00e7\u00f5es-Peixe Bravo n\u00e3o prev\u00ea Zona de Amortecimento (ZA) se limitando ao territ\u00f3rio indicado nos estudos e mapas<\/em>.\u201d<\/p>\n\n\n\n<p>Esta RDS \u00e9 imprescind\u00edvel para garantir os modos de vida das comunidades tradicionais em sinergia com o bioma Cerrado. No Brasil, esta RDS proposta \u00e9 a \u00fanica unidade de conserva\u00e7\u00e3o em vias de implementa\u00e7\u00e3o pelo governo federal no cerrado, bioma mais devastado e amea\u00e7ado nacionalmente. A \u00e1rea em quest\u00e3o \u00e9 de relev\u00e2ncia nacional e \u00e9 preciso que todo o pa\u00eds se empenhe na demarca\u00e7\u00e3o desse territ\u00f3rio como Reserva de Desenvolvimento Sustent\u00e1vel!<\/p>\n\n\n\n<p>O desenho da RDS garante a valoriza\u00e7\u00e3o das Comunidades Tradicionais e a conserva\u00e7\u00e3o do Cerrado. Al\u00e9m disso, a \u00e1rea garante a preserva\u00e7\u00e3o do \u00faltimo geosistema de canga ferruginosa no Brasil que n\u00e3o foi explorado pela minera\u00e7\u00e3o. A conserva\u00e7\u00e3o dessas \u00e1reas de cangas garante o volume e a qualidade de \u00e1gua para as comunidades, alimentando os rios Peixe Bravo, Vacaria e Jequitinhonha. Permitir a minera\u00e7\u00e3o e o avan\u00e7o da monocultura extensiva de eucalipto nessa regi\u00e3o vai colocar todo esse territ\u00f3rio, com sua rica sociobiodiversidade, em risco cada vez mais grave.<\/p>\n\n\n\n<p>A cria\u00e7\u00e3o desta RDS \u00e9 desejada e almejada por quem quer proteger o seu territ\u00f3rio da devasta\u00e7\u00e3o que as mineradoras, empreendimentos agropecu\u00e1rios, extensas planta\u00e7\u00f5es de eucalipto e todas as outras formas de avan\u00e7o do capitalismo superexplorador.<\/p>\n\n\n\n<p>No norte de Minas Gerais, a RDS Nascentes Geraizeiras, que acaba de completar 10 anos, \u00e9 um excelente exemplo do sucesso dessa modalidade de Unidade de Conserva\u00e7\u00e3o. &#8220;<em>O que a gente quer \u00e9 proteger o nosso modo de vida nas comunidades, com a nossa \u00e1gua limpa e pura, proteger os nossos rios e as nossas nascentes que s\u00e3o amea\u00e7ados por grandes projetos que n\u00e3o s\u00e3o ben\u00e9ficos para as comunidades<\/em>&#8220;, diz uma das lideran\u00e7as do Quilombo Peixe Bravo.&nbsp;<\/p>\n\n\n\n<p>Com a brutal devasta\u00e7\u00e3o ambiental em curso, os munic\u00edpios que tiverem RDS ganhar\u00e3o um ativo ambiental que lhes render\u00e3o muito em ICMS ECOL\u00d3GICO<a href=\"#_ftn4\" id=\"_ftnref4\">[4]<\/a>, em desenvolvimento de pol\u00edticas p\u00fablicas de ecoturismo comunit\u00e1rio, pesquisa cient\u00edfica etc. O ICMS ECOL\u00d3GICO, institu\u00eddo no estado de Minas Gerais pela Lei Estadual n\u00ba 18.030 de 2009, \u00e9 um crit\u00e9rio ambiental que visa distribuir uma parte da arrecada\u00e7\u00e3o do ICMS para os munic\u00edpios que tem Unidades de Conserva\u00e7\u00e3o, como RDS, com base em suas a\u00e7\u00f5es e investimentos na \u00e1rea ambiental.<\/p>\n\n\n\n<p>Nas Consultas P\u00fablicas coordenadas pelo ICMBio foi emocionante ver as comunidades recordarem o ensinamento e o testemunho do padre Ernesto de Freitas e do papa Francisco que evidenciam que h\u00e1 dois projetos em disputa, um de vida e outro de morte. Defender a implanta\u00e7\u00e3o da RDS C\u00f3rregos Po\u00e7\u00f5es-Tamandu\u00e1-Peixe Bravo \u00e9 defender as condi\u00e7\u00f5es de vida para as atuais e futuras gera\u00e7\u00f5es e para toda a biodiversidade. Por outro lado, apoiar o avan\u00e7o de minera\u00e7\u00e3o e de monocultura do eucalipto levar\u00e1 \u00e0 desertifica\u00e7\u00e3o da regi\u00e3o com consequ\u00eancias brutais para todo o Norte de Minas e o Vale do Jequitinhonha em Minas Gerais.<\/p>\n\n\n\n<p>Portanto, em nome da vida dos Povos, do Deus da vida e dos Direitos da Natureza, a implanta\u00e7\u00e3o da RDS C\u00f3rregos Po\u00e7\u00f5es-Tamandu\u00e1-Peixe bravo n\u00e3o \u00e9 apenas uma boa e justa proposta, mas se tornou uma necessidade para frearmos a avalanche de devasta\u00e7\u00e3o socioambiental. Ningu\u00e9m tem o direito de ser ego\u00edsta quando o bem comum est\u00e1 em jogo. RDS, j\u00e1!<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> Organiza\u00e7\u00e3o Internacional do Trabalho.<\/p>\n\n\n\n<p><a href=\"#_ftnref2\" id=\"_ftn2\">[2]<\/a> Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas.<\/p>\n\n\n\n<p><a href=\"#_ftnref3\" id=\"_ftn3\">[3]<\/a> <a href=\"https:\/\/www.gov.br\/icmbio\/pt-br\/assuntos\/criacao-de-unidades-de-conservacao\/lista-de-consultas-publicas\/nota-de-esclarecimento-consultas-publicas-para-a-criacao-da-reserva-de-desenvolvimento-sustentavel-rds-corregos-tamandua-pocoes-peixe-bravo\">https:\/\/www.gov.br\/icmbio\/pt-br\/assuntos\/criacao-de-unidades-de-conservacao\/lista-de-consultas-publicas\/nota-de-esclarecimento-consultas-publicas-para-a-criacao-da-reserva-de-desenvolvimento-sustentavel-rds-corregos-tamandua-pocoes-peixe-bravo<\/a><\/p>\n\n\n\n<p><a href=\"#_ftnref4\" id=\"_ftn4\">[4]<\/a> O Subscrit\u00e9rio Unidades de Conserva\u00e7\u00e3o est\u00e1 regulamentado pela&nbsp;<a href=\"http:\/\/www.siam.mg.gov.br\/sla\/download.pdf?idNorma=4167\" target=\"_blank\" rel=\"noreferrer noopener\">Resolu\u00e7\u00e3o SEMAD 318 de 2005&nbsp;<\/a>e&nbsp;<a href=\"https:\/\/liferay.meioambiente.mg.gov.br\/web\/ief\/w\/semad-e-ibama-firmam-acordo-para-compartilhar-gestao-da-fauna-em-minas-\" target=\"_blank\" rel=\"noreferrer noopener\">Resolu\u00e7\u00e3o SEMAD n\u00ba 1245 de 2010<\/a>, e possui como objetivo compensar os munic\u00edpios que possuem \u00e1reas protegidas em seu territ\u00f3rio e incentivar a cria\u00e7\u00e3o e implanta\u00e7\u00e3o de Unidades de Conserva\u00e7\u00e3o (UCs), como a RDS, al\u00e9m de melhorar a qualidade de gest\u00e3o dessas \u00e1reas.<\/p>\n\n\n\n<p>07\/05\/2025.<\/p>\n\n\n\n<p><strong>Obs<\/strong>.: A videorreportagem no link, abaixo, de alguma forma VERSAM sobre o assunto tratado, acima.<\/p>\n\n\n\n<p><strong>1 &#8211; AUDI\u00caNCIA P\u00daBLICA DO ICMBio: CRIA\u00c7\u00c3O DE RDS DE PO\u00c7\u00d5ES, TAMANDU\u00c1 E PEIXE BRAVO, NORTE DE MG. V\u00eddeo 1<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_97724\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/6gG-RS-F0jc?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>2 &#8211; DEP. BELLA E GERAIZEIROS APOIAM CRIA\u00c7\u00c3O DA RDS PO\u00c7\u00d5ES, TAMANDU\u00c1 E PEIXE BRAVO, NORTE DE MG. V\u00eddeo 2<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_35974\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/yofpYJkqMvY?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>3 &#8211; Dep. LENINHA APOIA CRIA\u00c7\u00c3O DA RDS DE PO\u00c7\u00d5ES\/TAMANDU\u00c1\/PEIXE BRAVO, MG. ICMBio: O QUE \u00c9 RDS? V\u00eddeo 3<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_88986\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/l25TOQn3d3Q?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>4 &#8211; ICMBio: QUE \u00c9 RDS, ONDE, CARACTER\u00cdSTICAS, COMO FUNCIONA E QUAIS BENEF\u00cdCIOS, no NORTE DE MG. V\u00eddeo 5<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_88970\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/GV2JuLVKCHk?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>5 &#8211; Dep. LELECO, Dep. LENINHA, Dep. Bella e Luzia APOIAM CRIA\u00c7\u00c3O DA RDS NO NORTE DE MG. VIDA! V\u00eddeo 6<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_48268\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/QEvD5G1Wx98?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>6 &#8211; FREI GILVANDER DEFENDE CRIA\u00c7\u00c3O DA RDS DE PO\u00c7\u00d5ES, TAMANDU\u00c1 E PEIXE BRAVO, NORTE DE MG. VIDA! V\u00eddeo 7<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_95565\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/wqksJ7EXqTA?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>7 &#8211; RDS DE PO\u00c7\u00d5ES\/TAMANDU\u00c1\/PEIXE BRAVO, NO NORTE DE MG PRESERVA NATUREZA, POVOS E AGRICULTURA. V\u00eddeo 8<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_33037\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/WxzbA6C3CdU?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>8 &#8211; MULHERES QUILOMBOLAS E GERAIZEIRAS: &#8220;RDS de PO\u00c7\u00d5ES-TAMANDU\u00c1-PEIXE BRAVO, NORTE DE MG, J\u00c1!&#8221; V\u00eddeo 9<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_45444\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/Uw8YFjuHJuI?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>9 &#8211; RDS BARRA MINERA\u00c7\u00c3O E MONOCULTURA DE EUCALIPTO, PRESERVA NATUREZA, POVOS E AGRICULTURA\/MG! V\u00eddeo 10<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_89621\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/IImY42YrDLo?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>10 &#8211; RDS \u00c9 COISA BOA E NECESS\u00c1RIA NO NORTE DE MG? SIM \u00c0 RDS DE PO\u00c7\u00d5ES, TAMANDU\u00c1 E PEIXE BRAVO! V\u00eddeo 11<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_70715\"  width=\"810\" height=\"456\"  data-origwidth=\"810\" data-origheight=\"456\" src=\"https:\/\/www.youtube.com\/embed\/CooVZd617oo?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> Doutor em Educa\u00e7\u00e3o pela FAE\/UFMG; Mestre em Ci\u00eancias B\u00edblicas; Bacharel e Licenciado em Filosofia; Bacharel em Teologia; frei e padre da Ordem dos Carmelitas; e Agente de Pastoral e Assessor da CPT\/MG (Comiss\u00e3o Pastoral da Terra \u2013 <a href=\"http:\/\/www.cptmg.org.br\">www.cptmg.org.br<\/a> ); e-mail: <a href=\"mailto:gilvanderlm@gmail.com\">gilvanderlm@gmail.com<\/a> \u2013 <a href=\"http:\/\/www.gilvander.org.br\">www.gilvander.org.br<\/a> \u2013 <a href=\"http:\/\/www.youtube.com\/@freigilvander\">www.youtube.com\/@freigilvander<\/a> \u2013 No instagram: @gilvanderluismoreira<\/p>\n\n\n\n<p><a href=\"#_ftnref2\" id=\"_ftn2\">[2]<\/a> Organiza\u00e7\u00e3o Internacional do Trabalho.<\/p>\n\n\n\n<p><a href=\"#_ftnref3\" id=\"_ftn3\">[3]<\/a> Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas.<\/p>\n\n\n\n<p><a href=\"#_ftnref4\" id=\"_ftn4\">[4]<\/a> <a href=\"https:\/\/www.gov.br\/icmbio\/pt-br\/assuntos\/criacao-de-unidades-de-conservacao\/lista-de-consultas-publicas\/nota-de-esclarecimento-consultas-publicas-para-a-criacao-da-reserva-de-desenvolvimento-sustentavel-rds-corregos-tamandua-pocoes-peixe-bravo\">https:\/\/www.gov.br\/icmbio\/pt-br\/assuntos\/criacao-de-unidades-de-conservacao\/lista-de-consultas-publicas\/nota-de-esclarecimento-consultas-publicas-para-a-criacao-da-reserva-de-desenvolvimento-sustentavel-rds-corregos-tamandua-pocoes-peixe-bravo<\/a><\/p>\n\n\n\n<p><a href=\"#_ftnref5\" id=\"_ftn5\">[5]<\/a> O Subscrit\u00e9rio Unidades de Conserva\u00e7\u00e3o est\u00e1 regulamentado pela&nbsp;<a href=\"http:\/\/www.siam.mg.gov.br\/sla\/download.pdf?idNorma=4167\" target=\"_blank\" rel=\"noreferrer noopener\">Resolu\u00e7\u00e3o SEMAD 318 de 2005&nbsp;<\/a>e&nbsp;<a href=\"https:\/\/liferay.meioambiente.mg.gov.br\/web\/ief\/w\/semad-e-ibama-firmam-acordo-para-compartilhar-gestao-da-fauna-em-minas-\" target=\"_blank\" rel=\"noreferrer noopener\">Resolu\u00e7\u00e3o SEMAD n\u00ba 1245 de 2010<\/a>, e possui como objetivo compensar os munic\u00edpios que possuem \u00e1reas protegidas em seu territ\u00f3rio e incentivar a cria\u00e7\u00e3o e implanta\u00e7\u00e3o de Unidades de Conserva\u00e7\u00e3o (UCs), como a RDS, al\u00e9m de melhorar a qualidade de gest\u00e3o dessas \u00e1reas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POR QUE \u00c9 JUSTO CRIAR RDS C\u00d3RREGOS PO\u00c7\u00d5ES-TAMANDU\u00c1-PEIXE BRAVO NO NORTE DE MINAS GERAIS? Por frei Gilvander Moreira[1] O direito ao meio ambiente ecologicamente equilibrado est\u00e1 na Constitui\u00e7\u00e3o, no Art. 225 que diz: \u201cTodos t\u00eam<\/p>\n","protected":false},"author":2,"featured_media":14437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,22,47,46,44,38,49,39,35,27,30,25,56,29,43,26,18],"tags":[],"class_list":["post-14436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","category-cebs-comunidades-eclesiais-de-base","category-direito-a-agua","category-direito-a-cultura-popular","category-direito-a-memoria","category-direito-a-saude","category-direito-a-terra","category-direitos-dos-povos-indigenas","category-direitos-dos-quilombolas","category-direitos-humanos","category-fe-e-politica","category-luta-pela-terra-e-reforma-agraria","category-meio-ambiente","category-movimentos-sociais-populares","category-pedagogia-emancipatoria","category-teologia-da-libertacao","category-videos-de-frei-gilvander"],"_links":{"self":[{"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/posts\/14436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/comments?post=14436"}],"version-history":[{"count":3,"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/posts\/14436\/revisions"}],"predecessor-version":[{"id":14444,"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/posts\/14436\/revisions\/14444"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/media\/14437"}],"wp:attachment":[{"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/media?parent=14436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/categories?post=14436"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gilvander.org.br\/site\/wp-json\/wp\/v2\/tags?post=14436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}